{"id":8994,"date":"2021-12-02T20:06:39","date_gmt":"2021-12-02T19:06:39","guid":{"rendered":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/?p=8994"},"modified":"2021-12-03T10:08:28","modified_gmt":"2021-12-03T09:08:28","slug":"materiallogistik-auf-den-baustellen-von-morgen-wieviel-design-verbirgt-sich-hinter-einem-solchen-konzept","status":"publish","type":"post","link":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/materiallogistik-auf-den-baustellen-von-morgen-wieviel-design-verbirgt-sich-hinter-einem-solchen-konzept\/","title":{"rendered":"Materiallogistik auf den Baustellen von morgen &#8211; wieviel Design verbirgt sich hinter einem solchen Konzept?"},"content":{"rendered":"<p>Industrie 4.0 steht f\u00fcr eine Aufholjagd der Bauindustrie, welche die dritte Industrielle Revolution verpasst hat. Flexible und intelligente Maschinen sollen die Prozesse auf Baustellen ihrer Zeit entsprechend endlich anpassen und erleichtern. Die vertikale Materialverteilung ist eine der zentralsten Herausforderungen der Baustellenlogistik, welche sich bis jetzt kaum umsetzen und in bestehende Prozessabl\u00e4ufe integrieren lie\u00df. Wer schon einmal bei einem Umzug dabei war, kann sich vielleicht vorstellen\u2026 Material in H\u00f6hen zu transportieren ist anstrengend.<\/p>\n<p>Der hier vorliegende Entwurf stellt dabei eine L\u00f6sung f\u00fcr die Transport- und Verteilungsprobleme auf beengten, innerst\u00e4dtischen Baustellen bereit. Das Konzept des Regalbedienger\u00e4ts aus dem Hochregallager, wurde konsequent auf die Baustelle transferiert und k\u00f6nnte den Grundstein f\u00fcr eine neue Baustellenlogistik legen.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-8995\" src=\"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-33.jpg\" alt=\"\" width=\"2222\" height=\"2963\" srcset=\"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-33.jpg 2222w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-33-250x333.jpg 250w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-33-768x1024.jpg 768w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-33-450x600.jpg 450w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-33-300x400.jpg 300w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-33-750x1000.jpg 750w\" sizes=\"(max-width: 2222px) 100vw, 2222px\" \/><\/p>\n<div>\n<p>Der Entwurf Besteht aus Mast, Hubwagen, Fahrwagen und Bodenstation. Dabei spielt die Gestaltung von Hub- und Fahrwagen die gestalterisch gr\u00f6\u00dfte Rolle. Der Hubwagen hat eine U-Form um auf der gro\u00dfen innen liegenden Fl\u00e4che die Lastaufnahmemittel aufnehmen zu k\u00f6nnen. In den senkrechten Volumina an den Seiten des K\u00f6rpers befinden sich die Bestandteile f\u00fcr den vertikalen Antrieb. Die vertikalen und die horizontalen Fl\u00e4chen werden durch ein Band zusammengehalten, das an den kurzen Seiten der 3-Grundk\u00f6rper entlangl\u00e4uft.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-8996\" src=\"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-34.jpg\" alt=\"\" width=\"6322\" height=\"7749\" srcset=\"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-34.jpg 6322w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-34-250x306.jpg 250w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-34-768x941.jpg 768w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-34-490x600.jpg 490w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-34-300x368.jpg 300w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-34-750x919.jpg 750w\" sizes=\"(max-width: 6322px) 100vw, 6322px\" \/><\/p>\n<div>\n<p>Der Fahrwagen baut auf derselben Grundform auf wie der Hubwagen. Sie ist jedoch um 90\u00b0 gekippt, so dass die U-Form die Masten umklammert. An der dazwischenliegenden Fl\u00e4che ist der Antrieb f\u00fcr die horizontale Bewegung des Systems angebracht. Der horizontale Antrieb besteht aus den Laufr\u00e4dern, welche angetrieben werden und den F\u00fchrungs- und Gegendruckrollen.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-8997\" src=\"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-32-1.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-32-1.jpg 2560w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-32-1-250x188.jpg 250w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-32-1-768x576.jpg 768w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-32-1-500x375.jpg 500w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-32-1-300x225.jpg 300w, https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/MicrosoftTeams-image-32-1-750x563.jpg 750w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<div>\n<p>Durch die tempor\u00e4re Lagerung von Materialien in der Regal-Konstruktion und gleichzeitig vertikalen Verteilung, kann die Baustellenlogistik optimiert werden. Wenn gro\u00dfe Mengen an Ladeeinheiten angeliefert werden, k\u00f6nnen diese im Ger\u00fcst zwischengelagert werden. Durch die neue Logistik k\u00f6nne Leerl\u00e4ufe besser einsch\u00e4tzen und gelagerte Lageeinheiten schnellstm\u00f6glich bereitstellen, sobald sie ben\u00f6tigt werde. So kommt es seltener zu Engp\u00e4ssen bei der vertikalen Verteilung.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Industrie 4.0 steht f\u00fcr eine Aufholjagd der Bauindustrie, welche die dritte Industrielle Revolution verpasst hat. Flexible und intelligente Maschinen sollen die Prozesse auf Baustellen ihrer Zeit entsprechend endlich anpassen und erleichtern. Die vertikale Materialverteilung ist eine der zentralsten Herausforderungen der Baustellenlogistik, welche sich bis jetzt kaum umsetzen und in bestehende Prozessabl\u00e4ufe integrieren lie\u00df. Wer schon [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8998,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6],"tags":[475,641,640],"_links":{"self":[{"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/8994"}],"collection":[{"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/comments?post=8994"}],"version-history":[{"count":3,"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/8994\/revisions"}],"predecessor-version":[{"id":9001,"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/8994\/revisions\/9001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/media\/8998"}],"wp:attachment":[{"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/media?parent=8994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/categories?post=8994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/tags?post=8994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}