{"id":439,"date":"2009-03-06T12:06:22","date_gmt":"2009-03-06T11:06:22","guid":{"rendered":"http:\/\/technischesdesign.wcms-file3.tu-dresden.de\/blog\/?p=439"},"modified":"2009-11-13T23:00:03","modified_gmt":"2009-11-13T22:00:03","slug":"schienengefuhrtes-uberwachungssystem","status":"publish","type":"post","link":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/schienengefuhrtes-uberwachungssystem\/","title":{"rendered":"Schienengef\u00fchrtes \u00dcberwachungssystem"},"content":{"rendered":"<p>Schienengef\u00fchrtes \u00dcberwachungssystem. Modularer Aufbau. Zusammenarbeit mit der Firma SEW Eurodrives.<\/p>\n<p>Bearbeiter: Dirk Haase<\/p>\n<p>Betreuer: Jens Krzywinski<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-440\" title=\"camtrain_haase\" src=\"http:\/\/technischesdesign.wcms-file3.tu-dresden.de\/blog\/wp-content\/uploads\/camtrain_haase.jpg\" alt=\"camtrain_haase\" width=\"500\" height=\"354\" srcset=\"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/camtrain_haase.jpg 500w, http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/camtrain_haase-300x212.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schienengef\u00fchrtes \u00dcberwachungssystem. Modularer Aufbau. Zusammenarbeit mit der Firma SEW Eurodrives. Bearbeiter: Dirk Haase Betreuer: Jens Krzywinski<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,4],"tags":[31,160,28,163],"_links":{"self":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/439"}],"collection":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":7,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/439\/revisions"}],"predecessor-version":[{"id":1792,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/439\/revisions\/1792"}],"wp:attachment":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/categories?post=439"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/tags?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}