{"id":356,"date":"2006-10-15T10:57:07","date_gmt":"2006-10-15T09:57:07","guid":{"rendered":"http:\/\/technischesdesign.wcms-file3.tu-dresden.de\/blog\/?p=356"},"modified":"2009-11-13T23:06:34","modified_gmt":"2009-11-13T22:06:34","slug":"konfektionierungsanlage-fur-abstandsgewirke","status":"publish","type":"post","link":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/konfektionierungsanlage-fur-abstandsgewirke\/","title":{"rendered":"Konfektionierungsanlage f\u00fcr Abstandsgewirke"},"content":{"rendered":"<p>Bearbeiter: Christian Knobloch<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-358\" title=\"knobloch_konfektionierung\" src=\"http:\/\/technischesdesign.wcms-file3.tu-dresden.de\/blog\/wp-content\/uploads\/knobloch_konfektionierung.jpg\" alt=\"knobloch_konfektionierung\" width=\"500\" height=\"256\" srcset=\"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/knobloch_konfektionierung.jpg 500w, http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-content\/uploads\/knobloch_konfektionierung-300x153.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bearbeiter: Christian Knobloch<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,4],"tags":[31,160,28,34],"_links":{"self":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/356"}],"collection":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":7,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"predecessor-version":[{"id":1804,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/posts\/356\/revisions\/1804"}],"wp:attachment":[{"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/technischesdesign.mw.tu-dresden.de\/blog\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}